{"id":58,"date":"2020-05-08T12:47:34","date_gmt":"2020-05-08T12:47:34","guid":{"rendered":"https:\/\/drogen.li\/?page_id=58"},"modified":"2025-12-29T19:58:52","modified_gmt":"2025-12-29T19:58:52","slug":"suchtpraevention-2","status":"publish","type":"page","link":"https:\/\/drogen.li\/","title":{"rendered":"PR\u00c4VENTION"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"58\" class=\"elementor elementor-58\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72688c26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72688c26\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0ff92e\" data-id=\"b0ff92e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-246e685b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"246e685b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+41332231781\" class=\"elementor-icon elementor-animation-pulse\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-phone-handset\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t033 223 17 81\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5ee7b67f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5ee7b67f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1850a2df\" data-id=\"1850a2df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75caa789 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"75caa789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\"\n\t\t\tdata-hamburger-icon=\"far fa-list-alt\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"1024\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                <i aria-hidden=\"true\" class=\"ekit-menu-icon far fa-list-alt\"><\/i>            <\/button>\n            <div id=\"ekit-megamenu-geteilt_menu_2\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-geteilt_menu_2\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-icon\"><li id=\"menu-item-2091\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-has-children menu-parent-item menu-item-2091 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/drogen.li\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">PR\u00c4VENTION<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-2551\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2551 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/drogen.li\/index.php\/drogen-sucht-praevention\/\" class=\" dropdown-item\">LINKS<\/a>\t<li id=\"menu-item-2093\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2093 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention-2\/aufklaerung-sucht-drogen-hiv\/\" class=\" dropdown-item\">WIESO ?<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-3920\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3920 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\" class=\"ekit-menu-nav-link\">Angebot<\/a><\/li>\n<li id=\"menu-item-2095\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2095 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/drogen.li\/index.php\/drogenpraevention\/\" class=\"ekit-menu-nav-link\">SPENDEN<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><a class=\"elementskit-nav-logo\" href=\"https:\/\/drogen.li\" target=\"\" rel=\"\"><img src=\"https:\/\/drogen.li\/wp-content\/uploads\/2020\/05\/placeholder.png\" title=\"\" alt=\"\" decoding=\"async\" \/><\/a><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-31053e60\" data-id=\"31053e60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36e82987 elementor-widget elementor-widget-image\" data-id=\"36e82987\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"247\" src=\"https:\/\/drogen.li\/wp-content\/uploads\/2020\/05\/Logo_Original_2020_ohne-BoxundSucht_neutral-300x247.png\" class=\"attachment-medium size-medium wp-image-2957\" alt=\"\" srcset=\"https:\/\/drogen.li\/wp-content\/uploads\/2020\/05\/Logo_Original_2020_ohne-BoxundSucht_neutral-300x247.png 300w, https:\/\/drogen.li\/wp-content\/uploads\/2020\/05\/Logo_Original_2020_ohne-BoxundSucht_neutral.png 766w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4d636392\" data-id=\"4d636392\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4033bba0 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"4033bba0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\"\n\t\t\tdata-hamburger-icon=\"far fa-list-alt\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"1024\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                <i aria-hidden=\"true\" class=\"ekit-menu-icon far fa-list-alt\"><\/i>            <\/button>\n            <div id=\"ekit-megamenu-geteilt-menue-1\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-geteilt-menue-1\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-icon\"><li id=\"menu-item-1197\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-parent-item menu-item-1197 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/drogen.li\/index.php\/suchtpraeevention-drogen-alkohol\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">KONTAKT<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-1198\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1198 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/drogen.li\/index.php\/suchtpraeevention-drogen-alkohol\/guestbook-hautnah\/\" class=\" dropdown-item\">G\u00c4STEBUCH<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-2543\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2543 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/drogen.li\/index.php\/alkohol-sucht-praevention\/\" class=\"ekit-menu-nav-link\">PRESSE<\/a><\/li>\n<li id=\"menu-item-1195\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-parent-item menu-item-1195 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/drogen.li\/index.php\/prevention-addiction\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">ENGLISH<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-1196\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1196 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/drogen.li\/index.php\/prevention-addiction\/donation-addiction-prevention-work\/\" class=\" dropdown-item\">DONATION<\/a><\/ul>\n<\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><a class=\"elementskit-nav-logo\" href=\"https:\/\/drogen.li\" target=\"\" rel=\"\"><img src=\"https:\/\/drogen.li\/wp-content\/uploads\/2020\/05\/placeholder.png\" title=\"\" alt=\"\" decoding=\"async\" \/><\/a><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2163478f elementor-section-stretched elementor-section-height-full elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"2163478f\" data-element_type=\"section\" data-e-type=\"section\" id=\"home\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-347300ac animated-slow elementor-invisible\" data-id=\"347300ac\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-45189d40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45189d40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6f0b13b\" data-id=\"6f0b13b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cb90758 elementor-widget elementor-widget-heading\" data-id=\"5cb90758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eins\u00e4tze in Schulen und anderen Organisationen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63cd480d elementor-widget elementor-widget-heading\" data-id=\"63cd480d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Drogen und Sucht Pr\u00e4vention die Jugendliche und Erwachsene w\u00fcnschen !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31bc4172 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"31bc4172\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c31887 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c31887\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5900d2f1\" data-id=\"5900d2f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-322ec0db elementor-widget elementor-widget-heading\" data-id=\"322ec0db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">In der ganzen Deutsch Schweiz<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-39f21fa3 elementor-widget elementor-widget-spacer\" data-id=\"39f21fa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-792de85f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"792de85f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-35bfe7dd\" data-id=\"35bfe7dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b387df4 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6b387df4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Angebote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-74f43452 elementor-widget elementor-widget-spacer\" data-id=\"74f43452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31a80893\" data-id=\"31a80893\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19caf0ab elementor-widget elementor-widget-spacer\" data-id=\"19caf0ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1658dae elementor-widget elementor-widget-spacer\" data-id=\"1658dae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a7779d0 elementor-section-content-middle elementor-section-stretched elementor-section-height-full elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5a7779d0\" data-element_type=\"section\" data-e-type=\"section\" id=\"about\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b41f39a\" data-id=\"7b41f39a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-54c8e312 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54c8e312\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-604f758a\" data-id=\"604f758a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-544909db elementor-widget elementor-widget-heading\" data-id=\"544909db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-medium\">Planung von Eins\u00e4tzen mit den Lehrkr\u00e4ften zusammen.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29c8556f elementor-widget elementor-widget-heading\" data-id=\"29c8556f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Angebote f\u00fcr Schulen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-47ad28d1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"47ad28d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54d7f436\" data-id=\"54d7f436\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26a51330 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"26a51330\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37b2a86 elementor-widget elementor-widget-text-editor\" data-id=\"37b2a86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ff6400; font-family: georgia, palatino, serif; font-size: 14pt;\"><a style=\"color: #ff6400;\" href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\">Antworten zur <\/a><\/span><\/p><p><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\"><small><big><span style=\"font-size: 18pt;\">Drogenpr\u00e4vention\u00a0 in der\u00a0 Schweiz, die Jugendliche und Erwachsene w\u00fcnschen.<\/span> <\/big><\/small><\/a><\/p><p><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\"><small><big><span style=\"font-size: 18pt;\">Zudem weitere Infos zu Sucht und HIV.<\/span><\/big><\/small><\/a><\/p><p style=\"text-align: center;\"><span style=\"color: #ff6600; font-size: 14pt;\"><a style=\"color: #ff6600;\" href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\">Suchtpr\u00e4vention f\u00fcr<\/a>\u00a0<\/span><\/p><p><span style=\"font-size: 12pt;\"><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\"><big><big>Jugendliche, Eltern, Lehrkr\u00e4fte, Mitarbeiter in Gemeinden, Jugendtreffs, Vereine, Firmen, Pfarreien und alle Interessierten, die sich mit der Problematik rund um Drogen, Sucht und HIV auseinandersetzen.<\/big><\/big><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70763b1a elementor-section-stretched elementor-section-full_width elementor-section-content-middle elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"70763b1a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f260094\" data-id=\"3f260094\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ba06e81 elementor-widget elementor-widget-spacer\" data-id=\"7ba06e81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a35328c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a35328c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-48c835c8\" data-id=\"48c835c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20d44b81 elementor-widget elementor-widget-heading\" data-id=\"20d44b81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcber uns!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f416b56 elementor-widget elementor-widget-heading\" data-id=\"f416b56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gr\u00fcndung des Vereins 1996<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a98e802 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1a98e802\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31ebfd53 elementor-widget elementor-widget-text-editor\" data-id=\"31ebfd53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\"><big><big>Der Verein wurde 1996 von Thomas Heller und Ueli Gasser (Dipl. Sozialarbeiter und Apotheker) in Thun gegr\u00fcndet. <\/big><\/big><\/a><\/p><p><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\"><big><big>Wir waren beide sehr stark mit der Sucht &#8211; problematik betroffen und darum der Name hautnah, im Vereins Namen. <\/big><\/big><\/a><\/p><p><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\"><big><big>In den Jahren seit der Gr\u00fcndung durften wir im Unterricht und an Elternabenden, \u00fc<span style=\"font-size: 18pt;\">ber <\/span><\/big><\/big><\/a><big><big><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\"><big><big><span style=\"font-size: 18pt;\">75`000 Jugendliche und Erwachsene unterrichten.<\/span> <\/big><\/big><\/a><\/big><\/big><\/p><p><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\"><big><big>Der Verein ist politisch und konfessionell neutral.<\/big><\/big><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-720dfc97 elementor-widget elementor-widget-spacer\" data-id=\"720dfc97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6faa0bc3 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6faa0bc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Angebote des Vereins<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1152c72 elementor-widget elementor-widget-spacer\" data-id=\"1152c72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-98b46d5\" data-id=\"98b46d5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-617d74d1 elementor-widget elementor-widget-spacer\" data-id=\"617d74d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3be0be23 elementor-section-stretched elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"3be0be23\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8bf22eb\" data-id=\"8bf22eb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5aa223c3 elementor-widget elementor-widget-spacer\" data-id=\"5aa223c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-104926a4\" data-id=\"104926a4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29368769 elementor-widget elementor-widget-spacer\" data-id=\"29368769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3445af7a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3445af7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54566c0\" data-id=\"54566c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48f5785d elementor-widget elementor-widget-heading\" data-id=\"48f5785d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mehr \u00fcber den Verein<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-712d6fa6 elementor-widget elementor-widget-heading\" data-id=\"712d6fa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mehr Infos und Kontakt\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71aa75a4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"71aa75a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-166acbfb elementor-widget elementor-widget-text-editor\" data-id=\"166acbfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\"><big><big>Unsere Angebote werden von Jugendlichen und Erwachsenen bei internen und externen Evaluationen, immer Top bewertet.<\/big><\/big><\/a><\/p><p><a href=\"https:\/\/drogen.li\/index.php\/suchtpraeevention-drogen-alkohol\/\"><big><big>Wenn Sie Unterlagen wie Konzepte, Evaluationen, Refernzlisten usw. w\u00fcnschen oder eine Testveranstaltung organisieren m\u00f6chten, k\u00f6nnen sie alles unverbindlich und Gratis \u00fcber unser Kontaktformular anfordern.<\/big><\/big><\/a><\/p><p><a href=\"https:\/\/drogen.li\/index.php\/suchtpraeevention-drogen-alkohol\/\"><big><big>Wir danken Ihnen f\u00fcr Ihr Interesse und w\u00fcrden uns freuen \u00fcber einen Erstkontakt<\/big><\/big><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-603c6a62 elementor-widget elementor-widget-spacer\" data-id=\"603c6a62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51e11909 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"51e11909\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/drogen.li\/index.php\/suchtpraeevention-drogen-alkohol\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontakt<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-711ef1c5 elementor-widget elementor-widget-spacer\" data-id=\"711ef1c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-539633fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"539633fa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4754a61d\" data-id=\"4754a61d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ef5210 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"7ef5210\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/drogen.li\/wp-content\/uploads\/2025\/12\/Broschuere-Drogen-Info-2025.pr_-1.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Drogen Info Kurz und b\u00fcndig<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d399b30 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7d399b30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/drogen.li\/index.php\/suchtpraeevention-drogen-alkohol\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-contact-form\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ea86b28 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3ea86b28\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e6a385d\" data-id=\"4e6a385d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e8a0f82 hfe-nav-menu__align-center hfe-submenu-icon-arrow hfe-submenu-animation-none hfe-link-redirect-child hfe-nav-menu__breakpoint-tablet elementor-widget elementor-widget-navigation-menu\" data-id=\"7e8a0f82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;width_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;220&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-horizontal hfe-nav-menu-layout horizontal hfe-pointer__none\" data-layout=\"horizontal\">\n\t\t\t\t<div role=\"button\" class=\"hfe-nav-menu__toggle elementor-clickable\" tabindex=\"0\" aria-label=\"Menu Toggle\">\n\t\t\t\t\t<span class=\"screen-reader-text\">Men\u00fc<\/span>\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\"  class=\"fas fa-align-justify\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-horizontal hfe-nav-menu__submenu-arrow\" data-toggle-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;fas fa-align-justify&quot;&gt;&lt;\/i&gt;\" data-close-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;far fa-window-close&quot;&gt;&lt;\/i&gt;\" data-full-width=\"yes\">\n\t\t\t\t\t<ul id=\"menu-1-7e8a0f82\" class=\"hfe-nav-menu\"><li id=\"menu-item-407\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-has-children menu-parent-item parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/drogen.li\/\" class = \"hfe-menu-item\">PR\u00c4VENTION<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-409\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention-2\/aufklaerung-sucht-drogen-hiv\/\" class = \"hfe-sub-menu-item\">WIESO ?<\/a><\/li>\n\t<li id=\"menu-item-2557\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/drogen.li\/index.php\/drogen-sucht-praevention\/\" class = \"hfe-sub-menu-item\">LINKS<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-410\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/drogen.li\/index.php\/suchtpraevention\/\" class = \"hfe-menu-item\">ANGEBOT<\/a><\/li>\n<li id=\"menu-item-416\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/drogen.li\/index.php\/drogenpraevention\/\" class = \"hfe-menu-item\">SPENDEN<\/a><\/li>\n<li id=\"menu-item-413\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-parent-item parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/drogen.li\/index.php\/suchtpraeevention-drogen-alkohol\/\" class = \"hfe-menu-item\">KONTAKT<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-1194\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/drogen.li\/index.php\/suchtpraeevention-drogen-alkohol\/guestbook-hautnah\/\" class = \"hfe-sub-menu-item\">G\u00c4STEBUCH<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-2558\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/drogen.li\/index.php\/alkohol-sucht-praevention\/\" class = \"hfe-menu-item\">PRESSE<\/a><\/li>\n<li id=\"menu-item-411\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-parent-item parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/drogen.li\/index.php\/prevention-addiction\/\" class = \"hfe-menu-item\">ENGLISH<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-412\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/drogen.li\/index.php\/prevention-addiction\/donation-addiction-prevention-work\/\" class = \"hfe-sub-menu-item\">DONATION<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul> \n\t\t\t\t<\/nav>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5443c751 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5443c751\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-348486d7\" data-id=\"348486d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f915222 mein-link elementor-widget elementor-widget-text-editor\" data-id=\"4f915222\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"tel:+41332231781\"><span style=\"color: #e9e9e9;\">VEREIN PR\u00c4VENTION HAUTNAH &#8211; FORSTWEG 60 &#8211; 3603 THUN &#8211; TEL: 033 223 17 <\/span><\/a><span style=\"color: #e9e9e9;\">81<\/span>\u00a0&#8211;<span style=\"color: #e9e9e9;\"><span style=\"color: #e9e9e9;\"><a style=\"color: #e9e9e9;\" href=\"tel:+41762273738\"> MOBILE: 076 227 37 38<\/a><\/span><br \/><\/span><\/p><p style=\"text-align: center;\"><span style=\"color: #e9e9e9;\">IBAN: CH33 0900 0000 3411 1111 0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>033 223 17 81 PR\u00c4VENTION LINKS WIESO ? Angebot SPENDEN X KONTAKT G\u00c4STEBUCH PRESSE ENGLISH DONATION X Eins\u00e4tze in Schulen und anderen Organisationen Drogen und Sucht Pr\u00e4vention die Jugendliche und Erwachsene w\u00fcnschen ! In der ganzen Deutsch Schweiz Angebote Planung von Eins\u00e4tzen mit den Lehrkr\u00e4ften zusammen. Angebote f\u00fcr Schulen Antworten zur Drogenpr\u00e4vention\u00a0 in der\u00a0 Schweiz, die Jugendliche und Erwachsene w\u00fcnschen. Zudem weitere Infos zu Sucht und HIV. Suchtpr\u00e4vention f\u00fcr\u00a0 Jugendliche, Eltern, Lehrkr\u00e4fte, Mitarbeiter in Gemeinden, Jugendtreffs, Vereine, Firmen, Pfarreien und alle Interessierten, die sich mit der Problematik rund um Drogen, Sucht und HIV auseinandersetzen. \u00dcber uns! Gr\u00fcndung des Vereins 1996 Der Verein wurde 1996 von Thomas Heller und Ueli Gasser (Dipl. Sozialarbeiter und Apotheker) in Thun gegr\u00fcndet. Wir waren beide sehr stark mit der Sucht &#8211; problematik betroffen und darum der Name hautnah, im Vereins Namen. In den Jahren seit der Gr\u00fcndung durften wir im Unterricht und an Elternabenden, \u00fcber&hellip;<\/p>\n<p> <a class=\"more-link\" href=\"https:\/\/drogen.li\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":247,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-58","page","type-page","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/drogen.li\/index.php\/wp-json\/wp\/v2\/pages\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drogen.li\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drogen.li\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drogen.li\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drogen.li\/index.php\/wp-json\/wp\/v2\/comments?post=58"}],"version-history":[{"count":186,"href":"https:\/\/drogen.li\/index.php\/wp-json\/wp\/v2\/pages\/58\/revisions"}],"predecessor-version":[{"id":4163,"href":"https:\/\/drogen.li\/index.php\/wp-json\/wp\/v2\/pages\/58\/revisions\/4163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drogen.li\/index.php\/wp-json\/wp\/v2\/media\/247"}],"wp:attachment":[{"href":"https:\/\/drogen.li\/index.php\/wp-json\/wp\/v2\/media?parent=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}